{"id":8262,"date":"2014-07-25T15:23:53","date_gmt":"2014-07-25T15:23:53","guid":{"rendered":"https:\/\/www.italpark.com\/prodotto\/panier-de-fruits-pierre-recomposee\/"},"modified":"2026-02-23T17:12:59","modified_gmt":"2026-02-23T16:12:59","slug":"panier-de-fruits-pierre-recomposee","status":"publish","type":"product","link":"https:\/\/www.italpark.com\/fr\/prodotto\/panier-de-fruits-pierre-recomposee\/","title":{"rendered":"corbeille de fruits"},"content":{"rendered":"<div style=\"text-align:justify;line-height:1.85;font-size:0.97em;border-left:6px solid #2D4F1D;padding-left:1.2em;\">\n<p>Le <strong>Panier de fruits<\/strong> est une \u00e9l\u00e9gante sculpture en pierre recompos\u00e9e qui repr\u00e9sente un panier de fruits. Sa forme met en valeur la beaut\u00e9 et la naturalit\u00e9 du design, tandis que la pierre recompos\u00e9e offre une r\u00e9sistance aux intemp\u00e9ries. Ce panier de fruits est un produit de haute qualit\u00e9, fabriqu\u00e9 en Italie avec soin et attention aux d\u00e9tails. Nous assurons des exp\u00e9ditions dans le monde entier, vous permettant de profiter de cette magnifique sculpture o\u00f9 que vous soyez.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>panier Cosy<\/strong> r\u00e9assembl\u00e9, cr\u00e9\u00e9 par Italpark pour r\u00e9pondre \u00e0 tous vos besoins.<\/p>\n<p><strong>Article 100% Made in Italy.<\/strong><\/p>\n","protected":false},"featured_media":43968,"template":"","meta":{"rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":""},"product_brand":[],"product_cat":[118],"product_tag":[],"class_list":["post-8262","product","type-product","status-publish","has-post-thumbnail","product_cat-cles-assortis","product_shipping_class-standard","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/product\/8262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/media\/43968"}],"wp:attachment":[{"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/media?parent=8262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.italpark.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}